{"id":999,"date":"2023-03-23T10:55:47","date_gmt":"2023-03-23T10:55:47","guid":{"rendered":"https:\/\/old.estudioletras.com\/?p=999"},"modified":"2024-02-27T17:49:46","modified_gmt":"2024-02-27T17:49:46","slug":"o-caso-do-marketplace-etsy-marketing-de-conteudo","status":"publish","type":"post","link":"https:\/\/old.estudioletras.com\/pt\/o-caso-do-marketplace-etsy-marketing-de-conteudo","title":{"rendered":"O caso do marketplace Etsy: quando o marketing de conte\u00fado entra em a\u00e7\u00e3o"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O artigo de hoje \u00e9, na verdade, um case de sucesso sobre o marketing de conte\u00fado aplicado pelo site Etsy. Para quem n\u00e3o sabe, esse \u00e9 um marketplace que oferece produtos vintages e manufaturados e re\u00fane v\u00e1rios vendedores e compradores em um \u00fanico lugar, como uma grande feira de artesanato online.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora o marketplace tenha aplicado v\u00e1rias estrat\u00e9gias de marketing, hoje queremos enfatizar aqui o <\/span><b>marketing de conte\u00fado<\/b><span style=\"font-weight: 400;\"> e apresentar brevemente o <\/span><b>estudo de caso do <a href=\"http:\/\/www.etsy.com\" target=\"_blank\" rel=\"noopener\">Etsy<\/a><\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos?\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Estudo de caso Etsy: o marketing de conte\u00fado aplicado<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00c9 claro que o site Etsy investiu em an\u00fancios, patrocinou eventos, realizou pesquisas de mercado e lan\u00e7ou m\u00e3o de v\u00e1rias outras estrat\u00e9gias importantes. Mas foi atrav\u00e9s do <\/span><b>marketing de conte\u00fado<\/b><span style=\"font-weight: 400;\"> que a empresa gerou valor para seus vendedores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em poucas palavras, podemos definir o marketing de conte\u00fado como uma ferramenta para atrair potenciais clientes por meio de conte\u00fados que sejam relevantes, interessantes e que ir\u00e3o solucionar os problemas do seu p\u00fablico-alvo, podendo ser um e-book, um v\u00eddeo, um artigo em um blog, um podcast ou mesmo nas redes sociais. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Repare que n\u00e3o estamos falando de promo\u00e7\u00e3o direta da marca, mas sim de entregar valor e oferecer formas de sanar as dores do seu cliente.\u00a0<\/span><\/p>\n<p><b>\u201cConte\u00fado excelente nos inspira a agir, a comprar algo que nem sab\u00edamos que precis\u00e1vamos. \u201d \u2013 Andrew Davis<\/b><\/p>\n<p><b>\u201cAs pessoas n\u00e3o amam um produto, elas amam o valor que ele adiciona a vida delas. O conte\u00fado mostra como. \u201d \u2013 Andrew Hanelly<\/b><\/p>\n<p><span style=\"font-weight: 400;\">E foi ao observar as necessidades de um nicho, que a Etsy percebeu que muitas pessoas queriam vender produtos manufaturados, mas n\u00e3o sabiam por onde come\u00e7ar. Assim, o marketplace elaborou uma estrat\u00e9gia que consistia em gerar valor para os sellers, com um guia pr\u00e1tico para vender online.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir da\u00ed eles conseguiram consolidar o site e crescer a ponto de competir com os gigantes Amazon Handmade e o eBay.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">A estrat\u00e9gia do Etsy na pr\u00e1tica<\/span><\/h2>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O primeiro passo foi focar e <\/span><b>segmentar um p\u00fablico espec\u00edfico<\/b><span style=\"font-weight: 400;\">: as pessoas comuns que queriam vender algo na internet, mas que n\u00e3o tinham ideia de como come\u00e7ar.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Oferecer conte\u00fado relevante para cada etapa da jornada dessas pessoas. Neste momento foram feitas <\/span><b>pesquisas de palavras-chave no Keyword Planner<\/b><span style=\"font-weight: 400;\"> para descobrirem quantas pessoas estavam interessadas no assunto e como pesquisavam na internet.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ao oferecer conte\u00fados valiosos sobre \u201ccomo vender na internet\u201d, por exemplo, o leitor precisava deixar seu e-mail para receber mais conte\u00fados sobre o assunto. E assim a Etsy come\u00e7ou a <strong>consolidar seu mailing de poss\u00edveis vendedores.\u00a0<\/strong><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Com os e-mails em m\u00e3os, o marketplace <strong>convertia o leitor em um seller<\/strong> para o seu site, mostrando as vantagens de vender seus produtos usados ou artesanais no Etsy.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Desta forma, <strong>o site estruturou a sua base de vendedores<\/strong> ao ensinar o passo-a-passo de como vender na internet.\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Esse estudo de caso da Etsy prova que vale a pena investir em conte\u00fado de qualidade. Sem contar que estabelecer uma rela\u00e7\u00e3o de confian\u00e7a com a comunidade \u00e9 a forma mais inteligente de entregar valor para aqueles que trazem a receita para a empresa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em uma entrevista em agosto de 2013, o CEO Chad Dickerson enfatizou a import\u00e2ncia da intera\u00e7\u00e3o humana e do significado da criatividade em rela\u00e7\u00e3o \u00e0 sua perspectiva sobre o Etsy. Dickerson descreveu o site como <strong>&#8220;uma plataforma que d\u00e1 significado \u00e0s pessoas, e uma oportunidade para validar sua arte, seu of\u00edcio&#8221;<\/strong>.<\/span><\/p>\n<p><strong>Leia tamb\u00e9m<\/strong>: <a href=\"https:\/\/old.estudioletras.com\/pt\/storytelling-e-as-narrativas-de-marca\/\">Storytelling e as narrativas de marca<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Invista em uma comunica\u00e7\u00e3o integrada!<\/h2>\n<p>Assim como o site Etsy, \u00e9 importante investir no marketing de conte\u00fado, mas tamb\u00e9m criar outras a\u00e7\u00f5es de marketing complementares, como o marketing de influ\u00eancia, fazer an\u00fancios Meta e Google Ads, por exemplo e trabalhar a comunica\u00e7\u00e3o em todos os pontos de contato com o potencial consumidor. Para isso, \u00e9 necess\u00e1rio planejamento e tempo.<\/p>","protected":false},"excerpt":{"rendered":"<p>O artigo de hoje \u00e9, na verdade, um case de sucesso sobre o marketing de conte\u00fado aplicado pelo site Etsy. Para quem n\u00e3o sabe, esse \u00e9 um marketplace que oferece produtos vintages e manufaturados e re\u00fane v\u00e1rios vendedores e compradores em um \u00fanico lugar, como&#8230;<\/p>","protected":false},"author":1,"featured_media":1528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[34],"tags":[35,60,61,36],"class_list":["post-999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","tag-estudo-de-caso-etsy","tag-etsy","tag-marketing-de-conteudo","tag-marketing-de-conteudo-etsy"],"acf":[],"_links":{"self":[{"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/posts\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/comments?post=999"}],"version-history":[{"count":4,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/posts\/999\/revisions"}],"predecessor-version":[{"id":1742,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/posts\/999\/revisions\/1742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/media?parent=999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/categories?post=999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/old.estudioletras.com\/pt\/wp-json\/wp\/v2\/tags?post=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}